{"id":630,"date":"2022-03-22T07:18:19","date_gmt":"2022-03-22T07:18:19","guid":{"rendered":"https:\/\/r3antiaging.com\/india\/?page_id=630"},"modified":"2024-10-07T13:50:09","modified_gmt":"2024-10-07T13:50:09","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/r3antiaging.com\/india\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"630\" class=\"elementor elementor-630\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7feaddc elementor-section-height-min-height elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no\" data-id=\"7feaddc\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-01da430\" data-id=\"01da430\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8f8981e elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"8f8981e\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2a70494\" data-id=\"2a70494\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb3368b elementor-widget elementor-widget-heading\" data-id=\"fb3368b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.1 - 13-11-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><p class=\"elementor-heading-title elementor-size-default\">CONTACT US<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-136c66e elementor-hidden-mobile\" data-id=\"136c66e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56ceda8 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"56ceda8\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2255d0\" data-id=\"f2255d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8bf6ea5 elementor-widget elementor-widget-heading\" data-id=\"8bf6ea5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Begin Your Anti-Aging<br\/>\nJourney Today<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76f7113 elementor-widget elementor-widget-text-editor\" data-id=\"76f7113\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.1 - 13-11-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>New patients receive a FREE consultation* and take advantage of our <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/r3antiaging.com\/india\/specials\/\" target=\"_blank\" rel=\"noopener\">SPECIALS HERE<\/a>!<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b039438 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"b039438\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c7af32f\" data-id=\"c7af32f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-696a457 elementor-widget elementor-widget-shortcode\" data-id=\"696a457\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">        <div class=\"r3contact_wrap\">\n            <div class=\"r3contact\">\n                <form class=\"ps_contact_form\" id=\"ps_contact_form\" method=\"post\">\n                    <div class=\"row\">\n                        <div class=\"col-md-12\">\n                            <div class=\"ps_loader\" style=\"display: none\"><\/div>\n                            <section class=\"r3contact_form_section\">\n                                <p class=\"con_message\"><\/p>\n\n                                                                    <div class=\"r3contact-form-group\">\n                                        <input id=\"first_name\" type=\"text\" class=\"r3contact_form_control required\"\n                                               name=\"first_name\" placeholder=\"First Name\">\n                                    <\/div>\n                                \n                                                                    <div class=\"r3contact-form-group\">\n                                        <input id=\"last_name\" type=\"text\" class=\"r3contact_form_control required\" name=\"last_name\"\n                                               placeholder=\"Last Name\">\n                                    <\/div>\n                                \n                                                                    <div class=\"r3contact-form-group\">\n                                        <input id=\"email\" type=\"text\" class=\"r3contact_form_control required\" name=\"email\"\n                                               placeholder=\"Email Address\">\n                                    <\/div>\n                                \n                                                                    <div class=\"r3contact-form-group\">\n                                        <div class=\"r3contact-input-group\">\n                                    <span class=\"input-group-addon\">\n                                      <select name=\"country_code\" id=\"country_code\" class=\"r3contact_form_control\">\n                                                                                    <option value=\"1\">US ( +1 ) <\/option>\n                                                                                    <option value=\"44\">UK ( +44 ) <\/option>\n                                                                                    <option value=\"376\">AD ( +376 ) <\/option>\n                                                                                    <option value=\"971\">AE ( +971 ) <\/option>\n                                                                                    <option value=\"93\">AF ( +93 ) <\/option>\n                                                                                    <option value=\"1268\">AG ( +1268 ) <\/option>\n                                                                                    <option value=\"1264\">AI ( +1264 ) <\/option>\n                                                                                    <option value=\"355\">AL ( +355 ) <\/option>\n                                                                                    <option value=\"374\">AM ( +374 ) <\/option>\n                                                                                    <option value=\"599\">AN ( +599 ) <\/option>\n                                                                                    <option value=\"244\">AO ( +244 ) <\/option>\n                                                                                    <option value=\"672\">AQ ( +672 ) <\/option>\n                                                                                    <option value=\"54\">AR ( +54 ) <\/option>\n                                                                                    <option value=\"1684\">AS ( +1684 ) <\/option>\n                                                                                    <option value=\"43\">AT ( +43 ) <\/option>\n                                                                                    <option value=\"61\">AU ( +61 ) <\/option>\n                                                                                    <option value=\"297\">AW ( +297 ) <\/option>\n                                                                                    <option value=\"994\">AZ ( +994 ) <\/option>\n                                                                                    <option value=\"387\">BA ( +387 ) <\/option>\n                                                                                    <option value=\"1246\">BB ( +1246 ) <\/option>\n                                                                                    <option value=\"880\">BD ( +880 ) <\/option>\n                                                                                    <option value=\"32\">BE ( +32 ) <\/option>\n                                                                                    <option value=\"226\">BF ( +226 ) <\/option>\n                                                                                    <option value=\"359\">BG ( +359 ) <\/option>\n                                                                                    <option value=\"973\">BH ( +973 ) <\/option>\n                                                                                    <option value=\"257\">BI ( +257 ) <\/option>\n                                                                                    <option value=\"229\">BJ ( +229 ) <\/option>\n                                                                                    <option value=\"590\">BL ( +590 ) <\/option>\n                                                                                    <option value=\"1441\">BM ( +1441 ) <\/option>\n                                                                                    <option value=\"673\">BN ( +673 ) <\/option>\n                                                                                    <option value=\"591\">BO ( +591 ) <\/option>\n                                                                                    <option value=\"55\">BR ( +55 ) <\/option>\n                                                                                    <option value=\"1242\">BS ( +1242 ) <\/option>\n                                                                                    <option value=\"975\">BT ( +975 ) <\/option>\n                                                                                    <option value=\"267\">BW ( +267 ) <\/option>\n                                                                                    <option value=\"375\">BY ( +375 ) <\/option>\n                                                                                    <option value=\"501\">BZ ( +501 ) <\/option>\n                                                                                    <option value=\"1\">CA ( +1 ) <\/option>\n                                                                                    <option value=\"61\">CC ( +61 ) <\/option>\n                                                                                    <option value=\"243\">CD ( +243 ) <\/option>\n                                                                                    <option value=\"236\">CF ( +236 ) <\/option>\n                                                                                    <option value=\"242\">CG ( +242 ) <\/option>\n                                                                                    <option value=\"41\">CH ( +41 ) <\/option>\n                                                                                    <option value=\"225\">CI ( +225 ) <\/option>\n                                                                                    <option value=\"682\">CK ( +682 ) <\/option>\n                                                                                    <option value=\"56\">CL ( +56 ) <\/option>\n                                                                                    <option value=\"237\">CM ( +237 ) <\/option>\n                                                                                    <option value=\"86\">CN ( +86 ) <\/option>\n                                                                                    <option value=\"57\">CO ( +57 ) <\/option>\n                                                                                    <option value=\"506\">CR ( +506 ) <\/option>\n                                                                                    <option value=\"53\">CU ( +53 ) <\/option>\n                                                                                    <option value=\"238\">CV ( +238 ) <\/option>\n                                                                                    <option value=\"61\">CX ( +61 ) <\/option>\n                                                                                    <option value=\"357\">CY ( +357 ) <\/option>\n                                                                                    <option value=\"420\">CZ ( +420 ) <\/option>\n                                                                                    <option value=\"49\">DE ( +49 ) <\/option>\n                                                                                    <option value=\"253\">DJ ( +253 ) <\/option>\n                                                                                    <option value=\"45\">DK ( +45 ) <\/option>\n                                                                                    <option value=\"1767\">DM ( +1767 ) <\/option>\n                                                                                    <option value=\"1809\">DO ( +1809 ) <\/option>\n                                                                                    <option value=\"213\">DZ ( +213 ) <\/option>\n                                                                                    <option value=\"593\">EC ( +593 ) <\/option>\n                                                                                    <option value=\"372\">EE ( +372 ) <\/option>\n                                                                                    <option value=\"20\">EG ( +20 ) <\/option>\n                                                                                    <option value=\"291\">ER ( +291 ) <\/option>\n                                                                                    <option value=\"34\">ES ( +34 ) <\/option>\n                                                                                    <option value=\"251\">ET ( +251 ) <\/option>\n                                                                                    <option value=\"358\">FI ( +358 ) <\/option>\n                                                                                    <option value=\"679\">FJ ( +679 ) <\/option>\n                                                                                    <option value=\"500\">FK ( +500 ) <\/option>\n                                                                                    <option value=\"691\">FM ( +691 ) <\/option>\n                                                                                    <option value=\"298\">FO ( +298 ) <\/option>\n                                                                                    <option value=\"33\">FR ( +33 ) <\/option>\n                                                                                    <option value=\"241\">GA ( +241 ) <\/option>\n                                                                                    <option value=\"1473\">GD ( +1473 ) <\/option>\n                                                                                    <option value=\"995\">GE ( +995 ) <\/option>\n                                                                                    <option value=\"233\">GH ( +233 ) <\/option>\n                                                                                    <option value=\"350\">GI ( +350 ) <\/option>\n                                                                                    <option value=\"299\">GL ( +299 ) <\/option>\n                                                                                    <option value=\"220\">GM ( +220 ) <\/option>\n                                                                                    <option value=\"224\">GN ( +224 ) <\/option>\n                                                                                    <option value=\"240\">GQ ( +240 ) <\/option>\n                                                                                    <option value=\"30\">GR ( +30 ) <\/option>\n                                                                                    <option value=\"502\">GT ( +502 ) <\/option>\n                                                                                    <option value=\"1671\">GU ( +1671 ) <\/option>\n                                                                                    <option value=\"245\">GW ( +245 ) <\/option>\n                                                                                    <option value=\"592\">GY ( +592 ) <\/option>\n                                                                                    <option value=\"852\">HK ( +852 ) <\/option>\n                                                                                    <option value=\"504\">HN ( +504 ) <\/option>\n                                                                                    <option value=\"385\">HR ( +385 ) <\/option>\n                                                                                    <option value=\"509\">HT ( +509 ) <\/option>\n                                                                                    <option value=\"36\">HU ( +36 ) <\/option>\n                                                                                    <option value=\"62\">ID ( +62 ) <\/option>\n                                                                                    <option value=\"353\">IE ( +353 ) <\/option>\n                                                                                    <option value=\"972\">IL ( +972 ) <\/option>\n                                                                                    <option value=\"44\">IM ( +44 ) <\/option>\n                                                                                    <option value=\"91\">IN ( +91 ) <\/option>\n                                                                                    <option value=\"964\">IQ ( +964 ) <\/option>\n                                                                                    <option value=\"98\">IR ( +98 ) <\/option>\n                                                                                    <option value=\"354\">IS ( +354 ) <\/option>\n                                                                                    <option value=\"39\">IT ( +39 ) <\/option>\n                                                                                    <option value=\"1876\">JM ( +1876 ) <\/option>\n                                                                                    <option value=\"962\">JO ( +962 ) <\/option>\n                                                                                    <option value=\"81\">JP ( +81 ) <\/option>\n                                                                                    <option value=\"254\">KE ( +254 ) <\/option>\n                                                                                    <option value=\"996\">KG ( +996 ) <\/option>\n                                                                                    <option value=\"855\">KH ( +855 ) <\/option>\n                                                                                    <option value=\"686\">KI ( +686 ) <\/option>\n                                                                                    <option value=\"269\">KM ( +269 ) <\/option>\n                                                                                    <option value=\"1869\">KN ( +1869 ) <\/option>\n                                                                                    <option value=\"850\">KP ( +850 ) <\/option>\n                                                                                    <option value=\"82\">KR ( +82 ) <\/option>\n                                                                                    <option value=\"965\">KW ( +965 ) <\/option>\n                                                                                    <option value=\"1345\">KY ( +1345 ) <\/option>\n                                                                                    <option value=\"7\">KZ ( +7 ) <\/option>\n                                                                                    <option value=\"856\">LA ( +856 ) <\/option>\n                                                                                    <option value=\"961\">LB ( +961 ) <\/option>\n                                                                                    <option value=\"1758\">LC ( +1758 ) <\/option>\n                                                                                    <option value=\"423\">LI ( +423 ) <\/option>\n                                                                                    <option value=\"94\">LK ( +94 ) <\/option>\n                                                                                    <option value=\"231\">LR ( +231 ) <\/option>\n                                                                                    <option value=\"266\">LS ( +266 ) <\/option>\n                                                                                    <option value=\"370\">LT ( +370 ) <\/option>\n                                                                                    <option value=\"352\">LU ( +352 ) <\/option>\n                                                                                    <option value=\"371\">LV ( +371 ) <\/option>\n                                                                                    <option value=\"218\">LY ( +218 ) <\/option>\n                                                                                    <option value=\"212\">MA ( +212 ) <\/option>\n                                                                                    <option value=\"377\">MC ( +377 ) <\/option>\n                                                                                    <option value=\"373\">MD ( +373 ) <\/option>\n                                                                                    <option value=\"382\">ME ( +382 ) <\/option>\n                                                                                    <option value=\"1599\">MF ( +1599 ) <\/option>\n                                                                                    <option value=\"261\">MG ( +261 ) <\/option>\n                                                                                    <option value=\"692\">MH ( +692 ) <\/option>\n                                                                                    <option value=\"389\">MK ( +389 ) <\/option>\n                                                                                    <option value=\"223\">ML ( +223 ) <\/option>\n                                                                                    <option value=\"95\">MM ( +95 ) <\/option>\n                                                                                    <option value=\"976\">MN ( +976 ) <\/option>\n                                                                                    <option value=\"853\">MO ( +853 ) <\/option>\n                                                                                    <option value=\"1670\">MP ( +1670 ) <\/option>\n                                                                                    <option value=\"222\">MR ( +222 ) <\/option>\n                                                                                    <option value=\"1664\">MS ( +1664 ) <\/option>\n                                                                                    <option value=\"356\">MT ( +356 ) <\/option>\n                                                                                    <option value=\"230\">MU ( +230 ) <\/option>\n                                                                                    <option value=\"960\">MV ( +960 ) <\/option>\n                                                                                    <option value=\"265\">MW ( +265 ) <\/option>\n                                                                                    <option value=\"52\">MX ( +52 ) <\/option>\n                                                                                    <option value=\"60\">MY ( +60 ) <\/option>\n                                                                                    <option value=\"258\">MZ ( +258 ) <\/option>\n                                                                                    <option value=\"264\">NA ( +264 ) <\/option>\n                                                                                    <option value=\"687\">NC ( +687 ) <\/option>\n                                                                                    <option value=\"227\">NE ( +227 ) <\/option>\n                                                                                    <option value=\"234\">NG ( +234 ) <\/option>\n                                                                                    <option value=\"505\">NI ( +505 ) <\/option>\n                                                                                    <option value=\"31\">NL ( +31 ) <\/option>\n                                                                                    <option value=\"47\">NO ( +47 ) <\/option>\n                                                                                    <option value=\"977\">NP ( +977 ) <\/option>\n                                                                                    <option value=\"674\">NR ( +674 ) <\/option>\n                                                                                    <option value=\"683\">NU ( +683 ) <\/option>\n                                                                                    <option value=\"64\">NZ ( +64 ) <\/option>\n                                                                                    <option value=\"968\">OM ( +968 ) <\/option>\n                                                                                    <option value=\"507\">PA ( +507 ) <\/option>\n                                                                                    <option value=\"51\">PE ( +51 ) <\/option>\n                                                                                    <option value=\"689\">PF ( +689 ) <\/option>\n                                                                                    <option value=\"675\">PG ( +675 ) <\/option>\n                                                                                    <option value=\"63\">PH ( +63 ) <\/option>\n                                                                                    <option value=\"92\">PK ( +92 ) <\/option>\n                                                                                    <option value=\"48\">PL ( +48 ) <\/option>\n                                                                                    <option value=\"508\">PM ( +508 ) <\/option>\n                                                                                    <option value=\"870\">PN ( +870 ) <\/option>\n                                                                                    <option value=\"1\">PR ( +1 ) <\/option>\n                                                                                    <option value=\"351\">PT ( +351 ) <\/option>\n                                                                                    <option value=\"680\">PW ( +680 ) <\/option>\n                                                                                    <option value=\"595\">PY ( +595 ) <\/option>\n                                                                                    <option value=\"974\">QA ( +974 ) <\/option>\n                                                                                    <option value=\"40\">RO ( +40 ) <\/option>\n                                                                                    <option value=\"381\">RS ( +381 ) <\/option>\n                                                                                    <option value=\"7\">RU ( +7 ) <\/option>\n                                                                                    <option value=\"250\">RW ( +250 ) <\/option>\n                                                                                    <option value=\"966\">SA ( +966 ) <\/option>\n                                                                                    <option value=\"677\">SB ( +677 ) <\/option>\n                                                                                    <option value=\"248\">SC ( +248 ) <\/option>\n                                                                                    <option value=\"249\">SD ( +249 ) <\/option>\n                                                                                    <option value=\"46\">SE ( +46 ) <\/option>\n                                                                                    <option value=\"65\">SG ( +65 ) <\/option>\n                                                                                    <option value=\"290\">SH ( +290 ) <\/option>\n                                                                                    <option value=\"386\">SI ( +386 ) <\/option>\n                                                                                    <option value=\"421\">SK ( +421 ) <\/option>\n                                                                                    <option value=\"232\">SL ( +232 ) <\/option>\n                                                                                    <option value=\"378\">SM ( +378 ) <\/option>\n                                                                                    <option value=\"221\">SN ( +221 ) <\/option>\n                                                                                    <option value=\"252\">SO ( +252 ) <\/option>\n                                                                                    <option value=\"597\">SR ( +597 ) <\/option>\n                                                                                    <option value=\"239\">ST ( +239 ) <\/option>\n                                                                                    <option value=\"503\">SV ( +503 ) <\/option>\n                                                                                    <option value=\"963\">SY ( +963 ) <\/option>\n                                                                                    <option value=\"268\">SZ ( +268 ) <\/option>\n                                                                                    <option value=\"1649\">TC ( +1649 ) <\/option>\n                                                                                    <option value=\"235\">TD ( +235 ) <\/option>\n                                                                                    <option value=\"228\">TG ( +228 ) <\/option>\n                                                                                    <option value=\"66\">TH ( +66 ) <\/option>\n                                                                                    <option value=\"992\">TJ ( +992 ) <\/option>\n                                                                                    <option value=\"690\">TK ( +690 ) <\/option>\n                                                                                    <option value=\"670\">TL ( +670 ) <\/option>\n                                                                                    <option value=\"993\">TM ( +993 ) <\/option>\n                                                                                    <option value=\"216\">TN ( +216 ) <\/option>\n                                                                                    <option value=\"676\">TO ( +676 ) <\/option>\n                                                                                    <option value=\"90\">TR ( +90 ) <\/option>\n                                                                                    <option value=\"1868\">TT ( +1868 ) <\/option>\n                                                                                    <option value=\"688\">TV ( +688 ) <\/option>\n                                                                                    <option value=\"886\">TW ( +886 ) <\/option>\n                                                                                    <option value=\"255\">TZ ( +255 ) <\/option>\n                                                                                    <option value=\"380\">UA ( +380 ) <\/option>\n                                                                                    <option value=\"256\">UG ( +256 ) <\/option>\n                                                                                    <option value=\"598\">UY ( +598 ) <\/option>\n                                                                                    <option value=\"998\">UZ ( +998 ) <\/option>\n                                                                                    <option value=\"39\">VA ( +39 ) <\/option>\n                                                                                    <option value=\"1784\">VC ( +1784 ) <\/option>\n                                                                                    <option value=\"58\">VE ( +58 ) <\/option>\n                                                                                    <option value=\"1284\">VG ( +1284 ) <\/option>\n                                                                                    <option value=\"1340\">VI ( +1340 ) <\/option>\n                                                                                    <option value=\"84\">VN ( +84 ) <\/option>\n                                                                                    <option value=\"678\">VU ( +678 ) <\/option>\n                                                                                    <option value=\"681\">WF ( +681 ) <\/option>\n                                                                                    <option value=\"685\">WS ( +685 ) <\/option>\n                                                                                    <option value=\"381\">XK ( +381 ) <\/option>\n                                                                                    <option value=\"967\">YE ( +967 ) <\/option>\n                                                                                    <option value=\"262\">YT ( +262 ) <\/option>\n                                                                                    <option value=\"27\">ZA ( +27 ) <\/option>\n                                                                                    <option value=\"260\">ZM ( +260 ) <\/option>\n                                                                                    <option value=\"263\">ZW ( +263 ) <\/option>\n                                                                              <\/select>\n                                    <\/span>\n                                            <input id=\"phone_number\" type=\"text\" class=\"r3contact_form_control required\" name=\"phone_number\" placeholder=\"Phone Number\">\n                                        <\/div>\n                                    <\/div>\n                                \n                                                                                                    <div class=\"r3contact-form-group\">\n                                        <input id=\"zip_code\" type=\"text\" class=\"r3contact_form_control required\" name=\"zip_code\"\n                                               placeholder=\"Zip Code\">\n                                    <\/div>\n                                                                                                    <div class=\"r3contact-form-group\">\n                                        <!--<label for=\"\">How did you hear about us?<\/label>-->\n                                        <select name=\"how_to_know\" id=\"how_to_know\" class=\"r3contact_form_control required\">\n                                             <option value=\"\">How did you hear about us?<\/option>\n                                            <option value=\"facebook\">Facebook<\/option>\n                                            <option value=\"instagram\">Instagram<\/option>\n                                            <option value=\"google\">Google<\/option>\n                                            <option value=\"tikTok\">TikTok<\/option>\n                                            <option value=\"youtube\">YouTube<\/option>\n                                            <option value=\"friend\">Friend\/Family<\/option>\n                                            <option value=\"other\">Other<\/option>\n                                        <\/select>\n                                    <\/div>\n                                \n                                                                    <div class=\"r3contact-form-group\">\n                                        <textarea rows=\"5\" id=\"message\" type=\"text\" class=\"r3contact_form_control required\" name=\"message\" placeholder=\"Message\"><\/textarea>\n                                    <\/div>\n                                \n                                \n                                <div class=\"google_recaptcha r3contact-form-group\">\n                                    <div class=\"g-recaptcha\" data-sitekey=\"6LciOucrAAAAAA6qa39LdEnTvdUGoN4ug16tAIjl\"><\/div>\n                                <\/div>\n                                                                    <div class=\"form-check r3contact-form-group\">\n                                        <input class=\"form-check-input terms_and_conditions required\" type=\"checkbox\"  name=\"terms_and_conditions\"\/>\n                                        <label class=\"form-check-label\" for=\"terms_and_conditions\">\n                                            I agree to receive marketing messages from the business. Message and data rates may apply. Message frequency varies. Text HELP for help. Text STOP to unsubscribe.                                        <\/label>\n                                    <\/div>\n                                \n                                                                    <div class=\"form-check r3contact-form-group\">\n                                        <input class=\"form-check-input terms_and_conditions_insurance required\" type=\"checkbox\"  name=\"terms_and_conditions_insurance\"\/>\n                                        <label class=\"form-check-label\" for=\"terms_and_conditions_insurance\">\n                                            I understand stem cell therapy is not covered by insurance and is paid out of pocket.                                        <\/label>\n                                    <\/div>\n                                \n                                                                    <div class=\"form-check r3contact-form-group\">\n                                        <input class=\"form-check-input terms_and_conditions_consent required\" type=\"checkbox\"  name=\"terms_and_conditions_consent\"\/>\n                                        <label class=\"form-check-label\" for=\"terms_and_conditions_insurance\">\n                                            I consent to R3 Stem Cell referencing the details of my message, including any health information I provide, when contacting me by phone, voicemail, email, or text.                                        <\/label>\n                                    <\/div>\n                                \n                                <input type=\"hidden\" name=\"r3contact_submit\" value=\"1\">\n                                                                    <input type=\"hidden\" name=\"location\" value=\"13\">\n                                                                <input type=\"hidden\" name=\"redirect_enable\" class=\"r3_redirect_enable\" value=\"yes\">\n                                                                    <input type=\"hidden\" name=\"redirect_url\" class=\"r3_redirect_url\" value=\"https:\/\/r3antiaging.com\/india\/thank-you\">\n                                                                                                <input type=\"hidden\" name=\"form_type\" value=\"contact_form\">\n                                <input type=\"hidden\" name=\"reporting_group\" id=\"reporting_group\" value=\"\">\n                                <input type=\"hidden\" name=\"ad_target_loc\" id=\"ad_target_loc\" value=\"\">\n                                <input type=\"hidden\" name=\"clinic_loc\" id=\"clinic_loc\" value=\"\">\n                                <input type=\"hidden\" name=\"utm_source\" id=\"utm_source\" value=\"\">\n                                <input type=\"hidden\" name=\"utm_medium\" id=\"utm_medium\" value=\"\">\n                                <input type=\"hidden\" name=\"utm_campaign\" id=\"utm_campaign\" value=\"\">\n                                <button type=\"submit\" class=\"r3contact-btn\"> Submit<\/button>\n                            <\/section>\n                        <\/div>\n                    <\/div>\n                <\/form>\n            <\/div>\n        <\/div>\n\n        <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e1a8db contact_iframe elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-html\" data-id=\"5e1a8db\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<iframe\r\n          src=\"https:\/\/link.r3medical.com\/widget\/form\/zRvMxagvtCUDC1M8qub0\"\r\n          style=\"width:100%;height:100%;border:none;border-radius:4px\"\r\n          id=\"inline-zRvMxagvtCUDC1M8qub0\"\r\n        data-layout=\"{'id':'INLINE'}\"\r\n        data-trigger-type=\"alwaysShow\"\r\n        data-trigger-value=\"\"\r\n        data-activation-type=\"alwaysActivated\"\r\n        data-activation-value=\"\"\r\n        data-deactivation-type=\"neverDeactivate\"\r\n        data-deactivation-value=\"\"\r\n        data-form-name=\"India: R3 Anti-Aging Website Form\"\r\n        data-height=\"664\"\r\n        data-layout-iframe-id=\"inline-zRvMxagvtCUDC1M8qub0\"\r\n        data-form-id=\"zRvMxagvtCUDC1M8qub0\"\r\n      >\r\n        <\/iframe>\r\n        <script src=\"https:\/\/link.r3medical.com\/js\/form_embed.js\"><\/script> \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-bff4a26\" data-id=\"bff4a26\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c85525b elementor-widget elementor-widget-google_maps\" data-id=\"c85525b\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.1 - 13-11-2022 *\/\n.elementor-widget-google_maps .elementor-widget-container{overflow:hidden}.elementor-widget-google_maps iframe{height:300px}<\/style>\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Y%2C%2049%2C%20Hauz%20Khas%20Rd%2C%20Block%20A%2C%20Hauz%20Khas%2C%20New%20Delhi%2C%20Delhi%20110016%2C%20India&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Y, 49, Hauz Khas Rd, Block A, Hauz Khas, New Delhi, Delhi 110016, India\"\n\t\t\t\t\taria-label=\"Y, 49, Hauz Khas Rd, Block A, Hauz Khas, New Delhi, Delhi 110016, India\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0a30fe elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"b0a30fe\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/r3antiaging.com\/india\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-box.min.css\">\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"hm hm-map-pointer2\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tR3 MEDICAL CLINIC PRIVATE LIMITED\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tGround floor, Y-49, INTRNAL<br>\n\nROAD, Near MCD School,<br>\n\nHauz Khas, New Delhi,<br>\n\nSouth Delhi, Delhi, 110016\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a01cde5 elementor-position-left elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"a01cde5\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"hm hm-map-pointer2\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\t135 Cleo Street\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCleo County, Sector 121<br\/>\nNoida, Uttar Pradesh, India\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c670d3d elementor-position-left elementor-view-default elementor-mobile-position-top elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"c670d3d\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"hm hm-phone\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tPhone\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t<a href=\"tel:+917947515066\"><b>+917947515066<\/b><\/a>\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1640859 elementor-widget elementor-widget-heading\" data-id=\"1640859\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Directions to R3 Anti Aging & Medspa Delhi, India<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f385706 elementor-widget elementor-widget-text-editor\" data-id=\"f385706\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>R3 is located in the Hauz Khas area of Delhi, India.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-80674e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"80674e8\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3356c23\" data-id=\"3356c23\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2021231 elementor-widget elementor-widget-text-editor\" data-id=\"2021231\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Y, 49, Hauz Khas Rd, <\/strong><br \/><strong>Block A, Hauz Khas, <\/strong><br \/><strong>New Delhi, Delhi 110016, India<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e888325 elementor-widget elementor-widget-text-editor\" data-id=\"e888325\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>If you have any issues finding us, please call <span style=\"color: #ffcc00;\"><b><a style=\"color: #ffcc00;\" href=\"tel:+917947515066\">+917947515066<\/a><\/b><\/span>.<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-eaa4698\" data-id=\"eaa4698\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6c8590 elementor-widget elementor-widget-text-editor\" data-id=\"b6c8590\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b576ca7 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"b576ca7\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4df92dc\" data-id=\"4df92dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc8a404 e-transform elementor-widget__width-auto elementor-fixed elementor-widget elementor-widget-qi_addons_for_elementor_button\" data-id=\"dc8a404\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:-90,&quot;sizes&quot;:[]},&quot;_position&quot;:&quot;fixed&quot;,&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"qi_addons_for_elementor_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<a class=\"qodef-shortcode qodef-m  qodef-qi-button qodef-html--link qodef-layout--filled qodef-type--icon-boxed   qodef-icon--right qodef-hover--icon-move-horizontal-short     \" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjU5MiIsInRvZ2dsZSI6ZmFsc2V9\" target=\"_self\">\n\t<span class=\"qodef-m-text\">Begin Your Anti-Aging Journey Today<\/span>\n\t\t<span class=\"qodef-m-icon \">\n\t\t<span class=\"qodef-m-icon-inner\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t\t<\/span>\n\t<\/span>\n<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5eb6514 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no elementor-invisible\" data-id=\"5eb6514\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-25e67ec\" data-id=\"25e67ec\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94196bd eael-flip-box--3d eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"94196bd\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-right eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <i aria-hidden=\"true\" class=\"ea-flipbox-icon hm hm-tick-circle\"><\/i>                                                                                    <\/div>\n                                                                        <h3 class=\"eael-elements-flip-box-heading\">BEAUTY TREATMENTS<\/h3>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                        <p><div class=\"ha-flip-box-front\"><div class=\"ha-flip-box-front-inner\"><div class=\"ha-text\"><p class=\"ha-desc\">Receive aesthetics treatments from our doctors who are experts at achieving your desired outcome! First rate hair restoration, facial rejuvenation, and sexual health procedures.<\/p><\/div><\/div><\/div><div class=\"ha-flip-box-back\"><div class=\"ha-flip-box-back-inner\">\u00a0<\/div><\/div><\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon hm hm-tick-circle\"><\/i>                                                <\/div>\n                                                                                                            <h3 class=\"eael-elements-flip-box-heading\">EXPERTS<\/h3>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                        <p><div class=\"ha-text\"><p class=\"ha-desc\">Our skilled doctors actually teach providers nationwide how to perform aesthetic procedures. Who better to receive treatment from than a highly skilled instructor!<\/p><\/div><\/p>\n                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/r3antiaging.com\/india\/services\/aesthetics\/\">\n                                                                                        CLICK HERE                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6b3d97b\" data-id=\"6b3d97b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c67faa7 eael-flip-box--3d eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"c67faa7\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-right eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <i aria-hidden=\"true\" class=\"ea-flipbox-icon hm hm-refresh\"><\/i>                                                                                    <\/div>\n                                                                        <h3 class=\"eael-elements-flip-box-heading\">SEXUAL HEALTH<\/h3>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                        <p><div class=\"ha-flip-box-front\"><div class=\"ha-flip-box-front-inner\"><div class=\"ha-text\"><div class=\"ha-text\"><p class=\"ha-desc\">Erectile dysfunction is incredibly common in adults, with an overall prevalence of 77%. R3 offers exceptionally effective therapies for ED, such as the E Shot, that will help men and couples thrive in the bedroom!<\/p><\/div><\/div><\/div><\/div><\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon hm hm-refresh\"><\/i>                                                <\/div>\n                                                                                                            <h3 class=\"eael-elements-flip-box-heading\">THE ED SOLUTION<\/h3>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                        <p><div class=\"ha-text\"><p class=\"ha-desc\">ED treatment needs to be customized for optimal results. R3 offers shockwave therapy, medications, PRP therapy with Growth Factors (E Shot), exosomes, stem cells and hyperbaric oxygen therapy.<\/p><\/div><\/p>\n                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/r3antiaging.com\/india\/services\/sexual-health\/\">\n                                                                                        CLICK HERE                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a728781\" data-id=\"a728781\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70242e2 eael-flip-box--3d eael-flipbox-content-align-center elementor-widget elementor-widget-eael-flip-box\" data-id=\"70242e2\" data-element_type=\"widget\" data-widget_type=\"eael-flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"eael-elements-flip-box-container eael-animate-flip eael-animate-right eael-content\">\n\n            <div class=\"eael-elements-flip-box-flip-card\">\n                <div class=\"eael-elements-flip-box-front-container\">\n\n                    \n                        <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                    <div class=\"eael-elements-flip-box-icon-image\">\n                                                                                    <i aria-hidden=\"true\" class=\"ea-flipbox-icon hm hm-shield\"><\/i>                                                                                    <\/div>\n                                                                        <h3 class=\"eael-elements-flip-box-heading\">STEM CELL THERAPY<\/h3>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                        <p><div class=\"ha-flip-box-front\"><div class=\"ha-flip-box-front-inner\"><div class=\"ha-text\"><div class=\"ha-text\"><p class=\"ha-desc\">R3 has been a leader globally with stem cell therapy for over a decade with 20,000 procedures in 10 years! This includes stem cell therapy in Delhi, India for patients that help with pain relief and improve quality of life.<\/p><\/div><\/div><\/div><\/div><\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <div class=\"eael-elements-flip-box-rear-container\">\n\n                                            <div class=\"eael-elements-slider-display-table\">\n                            <div class=\"eael-elements-flip-box-vertical-align\">\n                                <div class=\"eael-elements-flip-box-padding\">\n                                                                            <div class=\"eael-elements-flip-box-icon-image\">\n                                            <i aria-hidden=\"true\" class=\"ea-flipbox-icon hm hm-shield\"><\/i>                                                <\/div>\n                                                                                                            <h3 class=\"eael-elements-flip-box-heading\">EXOSOME THERAPY<\/h3>\n                                                                        <div class=\"eael-elements-flip-box-content\">\n                                        <p><div class=\"ha-text\"><p class=\"ha-desc\">R3 offers exosome therapies, which are top notch stem cell derived biologics that facilitate repair and regeneration in your body!<\/p><\/div><\/p>\n                                    <\/div>\n\n                                                                            <a class=\"flipbox-button\" href=\"https:\/\/r3antiaging.com\/india\/services\/regenerative-therapies\/\">\n                                                                                        CLICK HERE                                                                                            <\/a>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-ha-partstyle=\"nasa\" data-ha-partcolor=\"#FCCD7E\" data-ha-partopacity=\"10\" data-ha-partdirection=\"bottom\" class=\"elementor-section elementor-top-section elementor-element elementor-element-9fb4ef5 elementor-section-full_width elementor-section-stretched ha-particle-yes elementor-section-height-default elementor-section-height-default ha-particle-adv-no parallax_section_no qode_elementor_container_no\" data-id=\"9fb4ef5\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f31b07a elementor-hidden-mobile\" data-id=\"f31b07a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dd0d536\" data-id=\"dd0d536\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c772b1d elementor-widget elementor-widget-text-editor\" data-id=\"c772b1d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Sign up for special offers<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c67e69b elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"c67e69b\" data-element_type=\"widget\" data-settings=\"{&quot;button_width&quot;:&quot;20&quot;,&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor-pro - v3.11.0 - 13-02-2023 *\/\n.elementor-button.elementor-hidden,.elementor-hidden{display:none}.e-form__step{width:100%}.e-form__step:not(.elementor-hidden){display:flex;flex-wrap:wrap}.e-form__buttons{flex-wrap:wrap}.e-form__buttons,.e-form__buttons__wrapper{display:flex}.e-form__indicators{display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap;font-size:13px;margin-bottom:var(--e-form-steps-indicators-spacing)}.e-form__indicators__indicator{display:flex;flex-direction:column;align-items:center;justify-content:center;flex-basis:0;padding:0 var(--e-form-steps-divider-gap)}.e-form__indicators__indicator__progress{width:100%;position:relative;background-color:var(--e-form-steps-indicator-progress-background-color);border-radius:var(--e-form-steps-indicator-progress-border-radius);overflow:hidden}.e-form__indicators__indicator__progress__meter{width:var(--e-form-steps-indicator-progress-meter-width,0);height:var(--e-form-steps-indicator-progress-height);line-height:var(--e-form-steps-indicator-progress-height);padding-right:15px;border-radius:var(--e-form-steps-indicator-progress-border-radius);background-color:var(--e-form-steps-indicator-progress-color);color:var(--e-form-steps-indicator-progress-meter-color);text-align:right;transition:width .1s linear}.e-form__indicators__indicator:first-child{padding-left:0}.e-form__indicators__indicator:last-child{padding-right:0}.e-form__indicators__indicator--state-inactive{color:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-inactive [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-inactive-secondary-color,#fff)}.e-form__indicators__indicator--state-inactive object,.e-form__indicators__indicator--state-inactive svg{fill:var(--e-form-steps-indicator-inactive-primary-color,#c2cbd2)}.e-form__indicators__indicator--state-active{color:var(--e-form-steps-indicator-active-primary-color,#39b54a);border-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-active-secondary-color,#fff)}.e-form__indicators__indicator--state-active object,.e-form__indicators__indicator--state-active svg{fill:var(--e-form-steps-indicator-active-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed{color:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator--state-completed [class*=indicator--shape-]:not(.e-form__indicators__indicator--shape-none){background-color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator__label{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a)}.e-form__indicators__indicator--state-completed .e-form__indicators__indicator--shape-none{color:var(--e-form-steps-indicator-completed-primary-color,#39b54a);background-color:initial}.e-form__indicators__indicator--state-completed object,.e-form__indicators__indicator--state-completed svg{fill:var(--e-form-steps-indicator-completed-secondary-color,#fff)}.e-form__indicators__indicator__icon{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);font-size:var(--e-form-steps-indicator-icon-size);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;overflow:hidden;margin-bottom:10px}.e-form__indicators__indicator__icon img,.e-form__indicators__indicator__icon object,.e-form__indicators__indicator__icon svg{width:var(--e-form-steps-indicator-icon-size);height:auto}.e-form__indicators__indicator__icon .e-font-icon-svg{height:1em}.e-form__indicators__indicator__number{width:var(--e-form-steps-indicator-padding,30px);height:var(--e-form-steps-indicator-padding,30px);border-width:1px;border-style:solid;display:flex;justify-content:center;align-items:center;margin-bottom:10px}.e-form__indicators__indicator--shape-circle{border-radius:50%}.e-form__indicators__indicator--shape-square{border-radius:0}.e-form__indicators__indicator--shape-rounded{border-radius:5px}.e-form__indicators__indicator--shape-none{border:0}.e-form__indicators__indicator__label{text-align:center}.e-form__indicators__indicator__separator{width:100%;height:var(--e-form-steps-divider-width);background-color:#c2cbd2}.e-form__indicators--type-icon,.e-form__indicators--type-icon_text,.e-form__indicators--type-number,.e-form__indicators--type-number_text{align-items:flex-start}.e-form__indicators--type-icon .e-form__indicators__indicator__separator,.e-form__indicators--type-icon_text .e-form__indicators__indicator__separator,.e-form__indicators--type-number .e-form__indicators__indicator__separator,.e-form__indicators--type-number_text .e-form__indicators__indicator__separator{margin-top:calc(var(--e-form-steps-indicator-padding, 30px) \/ 2 - var(--e-form-steps-divider-width, 1px) \/ 2)}.elementor-field-type-hidden{display:none}.elementor-field-type-html{display:inline-block}.elementor-login .elementor-lost-password,.elementor-login .elementor-remember-me{font-size:.85em}.elementor-field-type-recaptcha_v3 .elementor-field-label{display:none}.elementor-field-type-recaptcha_v3 .grecaptcha-badge{z-index:1}.elementor-button .elementor-form-spinner{order:3}.elementor-form .elementor-button>span{display:flex;justify-content:center;align-items:center}.elementor-form .elementor-button .elementor-button-text{white-space:normal;flex-grow:0}.elementor-form .elementor-button svg{height:auto}.elementor-form .elementor-button .e-font-icon-svg{height:1em}.elementor-select-wrapper .select-caret-down-wrapper{position:absolute;top:50%;transform:translateY(-50%);inset-inline-end:10px;pointer-events:none;font-size:11px}.elementor-select-wrapper .select-caret-down-wrapper svg{display:unset;width:1em;aspect-ratio:unset;fill:currentColor}.elementor-select-wrapper .select-caret-down-wrapper i{font-size:19px;line-height:2}.elementor-select-wrapper.remove-before:before{content:\"\"!important}<\/style>\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"630\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"c67e69b\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"R3 Anti Aging &amp; Regenerative Orthopedics\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-field_3a4adb6 elementor-col-80\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3a4adb6\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[field_3a4adb6]\" id=\"form-field-field_3a4adb6\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Enter your email...\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-20 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm elementor-animation-buzz\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\" elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Send<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-43cd968 elementor-hidden-mobile\" data-id=\"43cd968\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cde68ea elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"cde68ea\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b6706dd\" data-id=\"b6706dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d7de00 elementor-widget elementor-widget-template\" data-id=\"7d7de00\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"210\" class=\"elementor elementor-210\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5232327 elementor-section-full_width elementor-section-height-min-height elementor-section-stretched footer_top_bg elementor-section-height-default elementor-section-items-middle parallax_section_no qode_elementor_container_no\" data-id=\"5232327\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a04116\" data-id=\"8a04116\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b35027 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"2b35027\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.1 - 13-11-2022 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/r3antiaging.com\/india\/wp-content\/uploads\/2022\/03\/footer_top_bg1.webp\" title=\"\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d788fb elementor-section-stretched footer_bttm elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"2d788fb\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79a2350\" data-id=\"79a2350\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d5391cf elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"d5391cf\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d6cff1a foot_col1\" data-id=\"d6cff1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-922c964 elementor-widget elementor-widget-image\" data-id=\"922c964\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/r3antiaging.com\/india\/wp-content\/uploads\/2022\/10\/R3_AntiAgingMedspa_Horizontal_White.png\" title=\"\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7005309 elementor-widget elementor-widget-text-editor\" data-id=\"7005309\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>R3 Anti Aging offers first rate PRP and IV therapies for aesthetics, joint pain, hair restoration, anti-aging and other ailments in New Delhi. Also, R3 offers hyperbaric oxygen, Botox\/Fillers and amazing treatments for erectile dysfunction!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbcb973 elementor-widget elementor-widget-text-editor\" data-id=\"cbcb973\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong><span class=\"il\">Disclaimer<\/span>:<\/strong> *Special offers are for new patients, one use only. Discounts cannot be combined. Offers available while supplies last, R3 reserves the right to discontinue at its discretion. There is a fee for HRT consultations.\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6c1946 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"a6c1946\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/r3antiaging.com\/india\/contact-us\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTACT US <\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a57b0cd foot_col2\" data-id=\"a57b0cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ec7ee5 elementor-widget elementor-widget-heading\" data-id=\"7ec7ee5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">MAIN MENU<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26122ff elementor-widget elementor-widget-qi_addons_for_elementor_separator\" data-id=\"26122ff\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_separator.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-qi-separator qodef-qi-clear qodef-separator--standard qodef-position--left\">\n\t<div class=\"qodef-m-line\"><\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94a2cc9 elementor-nav-menu__align-left footer_service_nav elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"94a2cc9\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/r3antiaging.com\/india\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-nav-menu.min.css\">\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-94a2cc9\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-725\"><a href=\"https:\/\/r3antiaging.com\/india\/\" class=\"elementor-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-726\"><a href=\"https:\/\/r3antiaging.com\/india\/why-r3\/\" class=\"elementor-item\">Why R3?<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-728\"><a href=\"https:\/\/r3antiaging.com\/india\/services\/\" class=\"elementor-item\">Services<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-727\"><a href=\"https:\/\/r3antiaging.com\/india\/contact-us\/\" class=\"elementor-item\">Contact Us<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-94a2cc9\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-725\"><a href=\"https:\/\/r3antiaging.com\/india\/\" class=\"elementor-item\" tabindex=\"-1\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-726\"><a href=\"https:\/\/r3antiaging.com\/india\/why-r3\/\" class=\"elementor-item\" tabindex=\"-1\">Why R3?<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-728\"><a href=\"https:\/\/r3antiaging.com\/india\/services\/\" class=\"elementor-item\" tabindex=\"-1\">Services<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-727\"><a href=\"https:\/\/r3antiaging.com\/india\/contact-us\/\" class=\"elementor-item\" tabindex=\"-1\">Contact Us<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-96e7f31 foot_col3\" data-id=\"96e7f31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db237b3 elementor-widget elementor-widget-heading\" data-id=\"db237b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">SERVICES<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96a5f73 elementor-widget elementor-widget-qi_addons_for_elementor_separator\" data-id=\"96a5f73\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_separator.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-qi-separator qodef-qi-clear qodef-separator--standard qodef-position--left\">\n\t<div class=\"qodef-m-line\"><\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c87de7a footer_service_nav elementor-nav-menu__text-align-aside elementor-widget elementor-widget-nav-menu\" data-id=\"c87de7a\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;dropdown&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-c87de7a\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2080\"><a href=\"https:\/\/r3antiaging.com\/india\/services\/facial-aesthetic-treatments-in-delhi\/\" class=\"elementor-item\" tabindex=\"-1\">Aesthetics<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2090\"><a href=\"https:\/\/r3antiaging.com\/india\/services\/facial-rejuvenation-treatment-in-delhi-ncr\/\" class=\"elementor-sub-item\" tabindex=\"-1\">PRP Facial &#038; Facelift<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2084\"><a href=\"https:\/\/r3antiaging.com\/india\/services\/non-surgical-hair-replacement-treatment-in-delhi-ncr\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Non Surgical Hair Replacement Delhi NCR<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2086\"><a href=\"https:\/\/r3antiaging.com\/india\/services\/hyperbaric-chamber-hyperbaric-oxygen-therapy-in-delhi\/\" class=\"elementor-item\" tabindex=\"-1\">Hyperbaric Oxygen<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2091\"><a href=\"https:\/\/r3antiaging.com\/india\/services\/regenerative-therapy-in-delhi\/\" class=\"elementor-item\" tabindex=\"-1\">Regenerative Therapies<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3841\"><a href=\"https:\/\/r3antiaging.com\/india\/services\/regenerative-therapy-in-delhi\/adipose-therapy-stem-cell-delhi\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Adipose Stem Cell Therapy<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-4284\"><a href=\"https:\/\/r3antiaging.com\/india\/services\/sexual-health-treatment\/\" class=\"elementor-item\" tabindex=\"-1\">Sexual Health<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2083\"><a href=\"https:\/\/r3antiaging.com\/india\/services\/erectile-dysfunction-treatment-in-delhi-ncr\/\" class=\"elementor-sub-item\" tabindex=\"-1\">erectile dysfunction treatment delhi ncr<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-5850\"><a href=\"https:\/\/r3antiaging.com\/india\/services\/iv-hydration-therapy-delhi-ncr\/\" class=\"elementor-item\" tabindex=\"-1\">IV Therapies<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-4831\"><a href=\"https:\/\/r3antiaging.com\/india\/iv-therapies\/myers-cocktail-scottsdale-az-nashville-tn\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Myers Cocktail<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5101\"><a href=\"https:\/\/r3antiaging.com\/india\/iv-therapies__trashed\/inner-beauty-medspa-iv-therapy-delhi\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Inner Beauty IV Therapy<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5196\"><a href=\"https:\/\/r3antiaging.com\/india\/iv-therapies__trashed\/recovery-performance-iv-drip-therapy-in-delhi\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Recovery &#038; Performance<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5275\"><a href=\"https:\/\/r3antiaging.com\/india\/iv-therapies__trashed\/hydrate-vitamin-iv-therapy-delhi\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Hydrate IV Drip Vitamin Therapy<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f2e0f3d foot_col4\" data-id=\"f2e0f3d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0792cc0 elementor-widget elementor-widget-heading\" data-id=\"0792cc0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">ADDRESS<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51f6e64 elementor-widget elementor-widget-qi_addons_for_elementor_separator\" data-id=\"51f6e64\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_separator.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-qi-separator qodef-qi-clear qodef-separator--standard qodef-position--left\">\n\t<div class=\"qodef-m-line\"><\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c73f20 footer_lastchild_padding footer_link elementor-widget elementor-widget-bridge_icon_list_item\" data-id=\"4c73f20\" data-element_type=\"widget\" data-widget_type=\"bridge_icon_list_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"q_icon_list\"><p style=\"color:#FFFFFF;font-size: 18px;font-weight: 700;\"><a href=\"tel:+917947515066\">+917947515066<\/a><\/p><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-051e48e elementor-widget elementor-widget-text-editor\" data-id=\"051e48e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>R3 MEDICAL CLINIC PRIVATE LIMITED<\/p><p>Ground floor, Y-49, INTRNAL<\/p><p>ROAD, Near MCD School,<\/p><p>Hauz Khas, New Delhi,<\/p><p>South Delhi, Delhi, 110016<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0f2751 elementor-widget elementor-widget-heading\" data-id=\"c0f2751\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">LET'S CONNECT<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-268b5e7 elementor-widget elementor-widget-qi_addons_for_elementor_separator\" data-id=\"268b5e7\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_separator.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-qi-separator qodef-qi-clear qodef-separator--standard qodef-position--left\">\n\t<div class=\"qodef-m-line\"><\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2580863 e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"2580863\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.1 - 13-11-2022 *\/\n.elementor-widget-social-icons.elementor-grid-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-mobile-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-tablet-0 .elementor-widget-container{line-height:1;font-size:0}.elementor-widget-social-icons:not(.elementor-grid-0):not(.elementor-grid-tablet-0):not(.elementor-grid-mobile-0) .elementor-grid{display:inline-grid}.elementor-widget-social-icons .elementor-grid{grid-column-gap:var(--grid-column-gap,5px);grid-row-gap:var(--grid-row-gap,5px);grid-template-columns:var(--grid-template-columns);-webkit-box-pack:var(--justify-content,center);-ms-flex-pack:var(--justify-content,center);justify-content:var(--justify-content,center);justify-items:var(--justify-content,center)}.elementor-icon.elementor-social-icon{font-size:var(--icon-size,25px);line-height:var(--icon-size,25px);width:calc(var(--icon-size, 25px) + (2 * var(--icon-padding, .5em)));height:calc(var(--icon-size, 25px) + (2 * var(--icon-padding, .5em)))}.elementor-social-icon{--e-social-icon-icon-color:#fff;display:-webkit-inline-box;display:-ms-inline-flexbox;display:inline-flex;background-color:#818a91;-webkit-box-align:center;-ms-flex-align:center;align-items:center;-webkit-box-pack:center;-ms-flex-pack:center;justify-content:center;text-align:center;cursor:pointer}.elementor-social-icon i{color:var(--e-social-icon-icon-color)}.elementor-social-icon svg{fill:var(--e-social-icon-icon-color)}.elementor-social-icon:last-child{margin:0}.elementor-social-icon:hover{opacity:.9;color:#fff}.elementor-social-icon-android{background-color:#a4c639}.elementor-social-icon-apple{background-color:#999}.elementor-social-icon-behance{background-color:#1769ff}.elementor-social-icon-bitbucket{background-color:#205081}.elementor-social-icon-codepen{background-color:#000}.elementor-social-icon-delicious{background-color:#39f}.elementor-social-icon-deviantart{background-color:#05cc47}.elementor-social-icon-digg{background-color:#005be2}.elementor-social-icon-dribbble{background-color:#ea4c89}.elementor-social-icon-elementor{background-color:#d30c5c}.elementor-social-icon-envelope{background-color:#ea4335}.elementor-social-icon-facebook,.elementor-social-icon-facebook-f{background-color:#3b5998}.elementor-social-icon-flickr{background-color:#0063dc}.elementor-social-icon-foursquare{background-color:#2d5be3}.elementor-social-icon-free-code-camp,.elementor-social-icon-freecodecamp{background-color:#006400}.elementor-social-icon-github{background-color:#333}.elementor-social-icon-gitlab{background-color:#e24329}.elementor-social-icon-globe{background-color:#818a91}.elementor-social-icon-google-plus,.elementor-social-icon-google-plus-g{background-color:#dd4b39}.elementor-social-icon-houzz{background-color:#7ac142}.elementor-social-icon-instagram{background-color:#262626}.elementor-social-icon-jsfiddle{background-color:#487aa2}.elementor-social-icon-link{background-color:#818a91}.elementor-social-icon-linkedin,.elementor-social-icon-linkedin-in{background-color:#0077b5}.elementor-social-icon-medium{background-color:#00ab6b}.elementor-social-icon-meetup{background-color:#ec1c40}.elementor-social-icon-mixcloud{background-color:#273a4b}.elementor-social-icon-odnoklassniki{background-color:#f4731c}.elementor-social-icon-pinterest{background-color:#bd081c}.elementor-social-icon-product-hunt{background-color:#da552f}.elementor-social-icon-reddit{background-color:#ff4500}.elementor-social-icon-rss{background-color:#f26522}.elementor-social-icon-shopping-cart{background-color:#4caf50}.elementor-social-icon-skype{background-color:#00aff0}.elementor-social-icon-slideshare{background-color:#0077b5}.elementor-social-icon-snapchat{background-color:#fffc00}.elementor-social-icon-soundcloud{background-color:#f80}.elementor-social-icon-spotify{background-color:#2ebd59}.elementor-social-icon-stack-overflow{background-color:#fe7a15}.elementor-social-icon-steam{background-color:#00adee}.elementor-social-icon-stumbleupon{background-color:#eb4924}.elementor-social-icon-telegram{background-color:#2ca5e0}.elementor-social-icon-thumb-tack{background-color:#1aa1d8}.elementor-social-icon-tripadvisor{background-color:#589442}.elementor-social-icon-tumblr{background-color:#35465c}.elementor-social-icon-twitch{background-color:#6441a5}.elementor-social-icon-twitter{background-color:#1da1f2}.elementor-social-icon-viber{background-color:#665cac}.elementor-social-icon-vimeo{background-color:#1ab7ea}.elementor-social-icon-vk{background-color:#45668e}.elementor-social-icon-weibo{background-color:#dd2430}.elementor-social-icon-weixin{background-color:#31a918}.elementor-social-icon-whatsapp{background-color:#25d366}.elementor-social-icon-wordpress{background-color:#21759b}.elementor-social-icon-xing{background-color:#026466}.elementor-social-icon-yelp{background-color:#af0606}.elementor-social-icon-youtube{background-color:#cd201f}.elementor-social-icon-500px{background-color:#0099e5}.elementor-shape-rounded .elementor-icon.elementor-social-icon{border-radius:10%}.elementor-shape-circle .elementor-icon.elementor-social-icon{border-radius:50%}<\/style>\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-animation-shrink elementor-repeater-item-569445f\" href=\"https:\/\/www.instagram.com\/r3antiaging_india\/?utm_source=ig_web_button_share_sheet&#038;igsh=ZDNlZDc0MzIxNw%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-animation-shrink elementor-repeater-item-8ebc0fd\" href=\"https:\/\/www.facebook.com\/r3antiagingindia\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-animation-shrink elementor-repeater-item-490c6f2\" href=\"https:\/\/www.youtube.com\/@R3AntiAgingIndia\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-youtube\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>CONTACT US Begin Your Anti-Aging Journey Today New patients receive a FREE consultation* and take advantage of our SPECIALS HERE! R3 MEDICAL CLINIC PRIVATE LIMITED Ground floor, Y-49, INTRNAL ROAD, Near MCD School, Hauz Khas, New Delhi, South Delhi, Delhi, 110016 135 Cleo Street Cleo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-630","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contact Us<\/title>\n<meta name=\"description\" content=\"CONTACT US Begin Your Anti-Aging Journey Today New patients receive a FREE consultation* and take advantage of our SPECIALS HERE! R3 MEDICAL CLINIC\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/r3antiaging.com\/india\/contact-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact Us\" \/>\n<meta property=\"og:description\" content=\"CONTACT US Begin Your Anti-Aging Journey Today New patients receive a FREE consultation* and take advantage of our SPECIALS HERE! R3 MEDICAL CLINIC\" \/>\n<meta property=\"og:url\" content=\"https:\/\/r3antiaging.com\/india\/contact-us\/\" \/>\n<meta property=\"og:site_name\" content=\"R3 Anti Aging &amp; Regenerative Orthopedics\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-07T13:50:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/r3antiaging.com\/india\/#organization\",\"name\":\"R3 ANTI AGING\",\"url\":\"https:\/\/r3antiaging.com\/india\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/r3antiaging.com\/india\/#logo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/r3antiaging.com\/india\/wp-content\/uploads\/2022\/05\/anti_aging_logo.png\",\"contentUrl\":\"https:\/\/r3antiaging.com\/india\/wp-content\/uploads\/2022\/05\/anti_aging_logo.png\",\"width\":260,\"height\":223,\"caption\":\"R3 ANTI AGING\"},\"image\":{\"@id\":\"https:\/\/r3antiaging.com\/india\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/r3antiaging.com\/india\/#website\",\"url\":\"https:\/\/r3antiaging.com\/india\/\",\"name\":\"R3 Anti Aging &amp; Regenerative Orthopedics\",\"description\":\"PRP for Aesthetics &amp; Joint Injections New Delhi\",\"publisher\":{\"@id\":\"https:\/\/r3antiaging.com\/india\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/r3antiaging.com\/india\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/r3antiaging.com\/india\/contact-us\/#webpage\",\"url\":\"https:\/\/r3antiaging.com\/india\/contact-us\/\",\"name\":\"Contact Us\",\"isPartOf\":{\"@id\":\"https:\/\/r3antiaging.com\/india\/#website\"},\"datePublished\":\"2022-03-22T07:18:19+00:00\",\"dateModified\":\"2024-10-07T13:50:09+00:00\",\"description\":\"CONTACT US Begin Your Anti-Aging Journey Today New patients receive a FREE consultation* and take advantage of our SPECIALS HERE! R3 MEDICAL CLINIC\",\"breadcrumb\":{\"@id\":\"https:\/\/r3antiaging.com\/india\/contact-us\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/r3antiaging.com\/india\/contact-us\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/r3antiaging.com\/india\/contact-us\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/r3antiaging.com\/india\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact Us\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact Us","description":"CONTACT US Begin Your Anti-Aging Journey Today New patients receive a FREE consultation* and take advantage of our SPECIALS HERE! R3 MEDICAL CLINIC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/r3antiaging.com\/india\/contact-us\/","og_locale":"en_US","og_type":"article","og_title":"Contact Us","og_description":"CONTACT US Begin Your Anti-Aging Journey Today New patients receive a FREE consultation* and take advantage of our SPECIALS HERE! R3 MEDICAL CLINIC","og_url":"https:\/\/r3antiaging.com\/india\/contact-us\/","og_site_name":"R3 Anti Aging &amp; Regenerative Orthopedics","article_modified_time":"2024-10-07T13:50:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/r3antiaging.com\/india\/#organization","name":"R3 ANTI AGING","url":"https:\/\/r3antiaging.com\/india\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/r3antiaging.com\/india\/#logo","inLanguage":"en-US","url":"https:\/\/r3antiaging.com\/india\/wp-content\/uploads\/2022\/05\/anti_aging_logo.png","contentUrl":"https:\/\/r3antiaging.com\/india\/wp-content\/uploads\/2022\/05\/anti_aging_logo.png","width":260,"height":223,"caption":"R3 ANTI AGING"},"image":{"@id":"https:\/\/r3antiaging.com\/india\/#logo"}},{"@type":"WebSite","@id":"https:\/\/r3antiaging.com\/india\/#website","url":"https:\/\/r3antiaging.com\/india\/","name":"R3 Anti Aging &amp; Regenerative Orthopedics","description":"PRP for Aesthetics &amp; Joint Injections New Delhi","publisher":{"@id":"https:\/\/r3antiaging.com\/india\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/r3antiaging.com\/india\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/r3antiaging.com\/india\/contact-us\/#webpage","url":"https:\/\/r3antiaging.com\/india\/contact-us\/","name":"Contact Us","isPartOf":{"@id":"https:\/\/r3antiaging.com\/india\/#website"},"datePublished":"2022-03-22T07:18:19+00:00","dateModified":"2024-10-07T13:50:09+00:00","description":"CONTACT US Begin Your Anti-Aging Journey Today New patients receive a FREE consultation* and take advantage of our SPECIALS HERE! R3 MEDICAL CLINIC","breadcrumb":{"@id":"https:\/\/r3antiaging.com\/india\/contact-us\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/r3antiaging.com\/india\/contact-us\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/r3antiaging.com\/india\/contact-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/r3antiaging.com\/india\/"},{"@type":"ListItem","position":2,"name":"Contact Us"}]}]}},"_links":{"self":[{"href":"https:\/\/r3antiaging.com\/india\/wp-json\/wp\/v2\/pages\/630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/r3antiaging.com\/india\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/r3antiaging.com\/india\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/r3antiaging.com\/india\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/r3antiaging.com\/india\/wp-json\/wp\/v2\/comments?post=630"}],"version-history":[{"count":45,"href":"https:\/\/r3antiaging.com\/india\/wp-json\/wp\/v2\/pages\/630\/revisions"}],"predecessor-version":[{"id":10576,"href":"https:\/\/r3antiaging.com\/india\/wp-json\/wp\/v2\/pages\/630\/revisions\/10576"}],"wp:attachment":[{"href":"https:\/\/r3antiaging.com\/india\/wp-json\/wp\/v2\/media?parent=630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}